{"id":40732,"date":"2019-08-16T12:37:00","date_gmt":"2019-08-16T17:37:00","guid":{"rendered":"https:\/\/growingupbilingual.com\/2019\/latino-parenting-es\/considering-a-short-term-loan-consider-these-facts-first\/"},"modified":"2019-08-16T14:14:04","modified_gmt":"2019-08-16T19:14:04","slug":"considering-a-short-term-loan-consider-these-facts-first","status":"publish","type":"post","link":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/","title":{"rendered":"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber."},"content":{"rendered":"<p style=\"font-weight: 400;\">Es dif\u00edcil de imaginar, pero un gran porcentaje de los estadounidenses no pueden obtener una tarjeta de cr\u00e9dito o un pr\u00e9stamo de un banco debido a que su calificaci\u00f3n crediticia es muy baja. Casi la mitad de las personas con una calificaci\u00f3n crediticia inferior a 680 son rechazadas cuando buscan nuevas l\u00edneas de cr\u00e9dito. Y el 44% de todos los estadounidenses no pueden cubrir los gastos de emergencia de $400. Para muchas personas, un pr\u00e9stamo a corto plazo puede ser la \u00fanica soluci\u00f3n.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#Porque_Esto_es_Importante_Para_Mi\" >Porque Esto es Importante Para Mi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#La_Amenaza_Financiera\" >La Amenaza Financiera<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#Manteniendo_el_Balance\" >Manteniendo el Balance<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#Como_Encontrar_un_Prestamista_Con_Buena_Reputacion\" >Como Encontrar un Prestamista Con Buena Reputaci\u00f3n<\/a><\/li><\/ul><\/nav><\/div>\n\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-40720\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/josh-appel-NeTPASr-bmQ-unsplash.jpg\" alt=\"Considering a Short-Term Loan? Consider These Facts First\" width=\"2048\" height=\"1538\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/josh-appel-NeTPASr-bmQ-unsplash.jpg 2048w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/josh-appel-NeTPASr-bmQ-unsplash-300x225.jpg 300w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/josh-appel-NeTPASr-bmQ-unsplash-768x577.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/josh-appel-NeTPASr-bmQ-unsplash-1024x769.jpg 1024w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/josh-appel-NeTPASr-bmQ-unsplash-500x375.jpg 500w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/josh-appel-NeTPASr-bmQ-unsplash-560x421.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/josh-appel-NeTPASr-bmQ-unsplash-600x451.jpg 600w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Porque_Esto_es_Importante_Para_Mi\"><\/span>Porque Esto es Importante Para Mi<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Cuando me mud\u00e9 a los Estados Unidos hace 11 a\u00f1os, tuvimos que comenzar desde cero y ni mi esposo ni yo ten\u00edamos historial crediticio. Mi familia vivi\u00f3 de salario en salario por a\u00f1os, siempre temiendo lo que suceder\u00eda si ocurriera una emergencia y nos enfrentamos a un gasto inesperado. Puesto que no ten\u00edamos ahorros, una emergencia financiera, como da\u00f1os a nuestra casa o la necesidad de reparar nuestro \u00fanico autom\u00f3vil, nos habr\u00eda devastado. Esta es la realidad para muchas familias y a\u00fan m\u00e1s para muchos hispanos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-40716\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368.jpg\" alt=\"Why This Matters To Me When I moved to the United States 11 years ago, I was forced to start from scratch with no credit history. My family lived paycheck to paycheck for years, always in fear of what would happen if an emergency occurred and we were faced with a big expense. With no savings to our name, a financial emergency \u2013 like damage to our home or the need to repair our only car \u2013 would have devastated us. This is the reality for many families and even more so for many Hispanics.\" width=\"1600\" height=\"1600\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368.jpg 1600w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368-150x150.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368-300x300.jpg 300w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368-768x768.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368-1024x1024.jpg 1024w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368-500x500.jpg 500w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368-560x560.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368-600x600.jpg 600w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368-100x100.jpg 100w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"La_Amenaza_Financiera\"><\/span><strong>La Amenaza Financiera <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Si bien un pr\u00e9stamo a corto plazo es, actualmente, una opci\u00f3n viable para muchas familias de bajos recursos, un grupo de legisladores est\u00e1 decidiendo si los consumidores de bajos recursos pueden tener cr\u00e9dito y cu\u00e1ndo pueden hacerlo.<\/p>\n<p>Estos legisladores est\u00e1n respaldados por prestamistas que ofrecen prestamos con bajos intereses. Estos prestamistas pueden mantener sus tasas de inter\u00e9s m\u00e1s bajas al amortiguar sus contratos con productos complementarios ocultos como el seguro de cr\u00e9dito.<\/p>\n<p>Esto significa que las familias de bajos recursos de los Estados Unidos, muchas de las cuales son hispanas, perder\u00e1n la oportunidad de trabajar con prestamistas que son transparentes con sus tarifas y se preocupan por el consumidor y se ver\u00e1n obligados a trabajar con prestamistas no regulados o poco \u00e9ticos.<\/p>\n<p>Si estos legisladores logran aprobar la legislaci\u00f3n propuesta, una de las fuentes m\u00e1s confiables de cr\u00e9dito r\u00e1pido para familias trabajadoras desaparecer\u00eda este a\u00f1o y ser\u00eda reemplazada por prestamistas que ofrecen atractivas tasas de inter\u00e9s bajas vinculadas a contratos poco transparentes llenos de tarifas ocultas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-40724\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/fabian-blank-pElSkGRA2NU-unsplash.jpg\" alt=\"Considering a Short-Term Loan? Consider These Facts First\" width=\"2048\" height=\"1365\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/fabian-blank-pElSkGRA2NU-unsplash.jpg 2048w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/fabian-blank-pElSkGRA2NU-unsplash-300x200.jpg 300w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/fabian-blank-pElSkGRA2NU-unsplash-768x512.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/fabian-blank-pElSkGRA2NU-unsplash-1024x683.jpg 1024w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/fabian-blank-pElSkGRA2NU-unsplash-560x373.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/fabian-blank-pElSkGRA2NU-unsplash-600x400.jpg 600w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<p>Es importante informarse para comprender la legislaci\u00f3n propuesta y todas sus repercusiones e implicaciones. <a href=\"https:\/\/www.realclearmarkets.com\/articles\/2019\/06\/%2012\/interest_rate_caps_dont_protect_borrowers_they_%20just_make_borrowing_difficult_103777.html\">Este art\u00edculo<\/a> explica c\u00f3mo los l\u00edmites de las tasas de inter\u00e9s no protegen realmente al consumidor, sino que solamente dificultan el aplicar a un pr\u00e9stamo. Esto, a su vez, pone a las familias necesitadas en una situaci\u00f3n m\u00e1s dif\u00edcil cuando se trata de sus opciones para cubrir cualquier gasto de emergencia. Al igual que el autor de <a href=\"https:\/\/www.sacbee.com\/opinion\/op-ed\/article231477123.html\">este art\u00edculo<\/a>, estoy de acuerdo en que la legislaci\u00f3n necesita proteger a los consumidores, pero tambi\u00e9n es importante tener en cuenta que la legislaci\u00f3n que elimina la opci\u00f3n de pr\u00e9stamos a corto plazo accesibles y regulados pone a las personas que dependen de ellos, muchos de ellos latinos, en una situaci\u00f3n muy dif\u00edcil.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Manteniendo_el_Balance\"><\/span>Manteniendo el Balance<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Al adquirir un pr\u00e9stamo a corto plazo, puede ser f\u00e1cil dejarse enga\u00f1ar por la oferta de una tasa de inter\u00e9s m\u00e1s baja. Pero es importante tomar en consideraci\u00f3n c\u00f3mo estos prestamistas pueden ofrecer tasas mucho m\u00e1s bajas que sus competidores. Para obtener ganancias, se ven obligados a incluir multas y tarifas ocultas dentro de sus contratos para extorsionar m\u00e1s dinero a sus clientes.<\/p>\n<p>Alternativamente, los prestamistas con mucha necesidad de efectivo r\u00e1pido pueden pasar por alto a los prestamistas acreditados que cobran una tasa de inter\u00e9s m\u00e1s alta. Al considerar un pr\u00e9stamo, debemos recordar que todos tenemos derecho a la transparencia, y tenemos derecho de conocer todos los costos, tarifas, tasas de inter\u00e9s y t\u00e9rminos asociados con un pr\u00e9stamo. No hay que dejarse enga\u00f1ar por prestamistas que ofrecen bajos inter\u00e9s que viene con condiciones adicionales o productos complementarios innecesarios, como el seguro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-40718\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_1847.jpg\" alt=\"Considering a Short-Term Loan? Consider These Facts First\" width=\"2048\" height=\"2731\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_1847.jpg 2048w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_1847-225x300.jpg 225w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_1847-768x1024.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_1847-560x747.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_1847-600x800.jpg 600w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Como_Encontrar_un_Prestamista_Con_Buena_Reputacion\"><\/span>Como Encontrar un Prestamista Con Buena Reputaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Para encontrar un prestamista con buena reputaci\u00f3n para un pr\u00e9stamo a corto plazo hay que poder separar la publicidad y los trucos de la realidad. Todav\u00eda hay instituciones financieras que apoyan los derechos de los prestamistas a la transparencia y la privacidad. Durante el proceso de solicitud de pr\u00e9stamo, haga preguntas puntuales sobre los t\u00e9rminos del pr\u00e9stamo, las tasas de inter\u00e9s y las tarifas asociadas. Y antes de firmar un pr\u00e9stamo personal, lea detenidamente el contrato asociado con el pr\u00e9stamo para asegurarse de que no haya malentendidos sobre lo que se espera de usted y el prestamista con el que est\u00e1 trabajando.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-40736\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/Copy-of-Copy-of-Why-You-Should-Go-To-Great-Beach.jpg\" alt=\"\" width=\"735\" height=\"1102\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/Copy-of-Copy-of-Why-You-Should-Go-To-Great-Beach.jpg 735w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/Copy-of-Copy-of-Why-You-Should-Go-To-Great-Beach-200x300.jpg 200w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/Copy-of-Copy-of-Why-You-Should-Go-To-Great-Beach-683x1024.jpg 683w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/Copy-of-Copy-of-Why-You-Should-Go-To-Great-Beach-560x840.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/Copy-of-Copy-of-Why-You-Should-Go-To-Great-Beach-600x900.jpg 600w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es dif\u00edcil de imaginar, pero un gran porcentaje de los estadounidenses no pueden obtener una tarjeta de cr\u00e9dito o un pr\u00e9stamo de un banco debido a que su calificaci\u00f3n crediticia es muy baja. Casi la mitad de las personas con una calificaci\u00f3n crediticia inferior a 680 son rechazadas cuando buscan nuevas l\u00edneas de cr\u00e9dito. Y &#8230; <a title=\"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.\" class=\"read-more\" href=\"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/\" aria-label=\"Leer m\u00e1s sobre \u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":40717,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"disable-jtr":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[6435],"tags":[],"class_list":["post-40732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finance-es","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.\" \/>\n<meta property=\"og:description\" content=\"Es dif\u00edcil de imaginar, pero un gran porcentaje de los estadounidenses no pueden obtener una tarjeta de cr\u00e9dito o un pr\u00e9stamo de un banco debido a que su calificaci\u00f3n crediticia es muy baja. Casi la mitad de las personas con una calificaci\u00f3n crediticia inferior a 680 son rechazadas cuando buscan nuevas l\u00edneas de cr\u00e9dito. Y ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/\" \/>\n<meta property=\"og:site_name\" content=\"Growing Up Bilingual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GrowUpBilingual\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-16T17:37:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-16T19:14:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368.jpg?fit=1600%2C1600&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paula Bendfeldt-Diaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrowUpBilingual\" \/>\n<meta name=\"twitter:site\" content=\"@GrowUpBilingual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paula Bendfeldt-Diaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/\"},\"author\":{\"name\":\"Paula Bendfeldt-Diaz\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#\\\/schema\\\/person\\\/38bc5392534f86f23648e73caa28f6ff\"},\"headline\":\"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.\",\"datePublished\":\"2019-08-16T17:37:00+00:00\",\"dateModified\":\"2019-08-16T19:14:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/\"},\"wordCount\":814,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/IMG_0368.jpg\",\"articleSection\":[\"Finance\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/\",\"name\":\"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/IMG_0368.jpg\",\"datePublished\":\"2019-08-16T17:37:00+00:00\",\"dateModified\":\"2019-08-16T19:14:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/#primaryimage\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/IMG_0368.jpg\",\"contentUrl\":\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/IMG_0368.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"Why This Matters To Me When I moved to the United States 11 years ago, I was forced to start from scratch with no credit history. My family lived paycheck to paycheck for years, always in fear of what would happen if an emergency occurred and we were faced with a big expense. With no savings to our name, a financial emergency \u2013 like damage to our home or the need to repair our only car \u2013 would have devastated us. This is the reality for many families and even more so for many Hispanics.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/considering-a-short-term-loan-consider-these-facts-first\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/\",\"name\":\"Growing Up Bilingual\",\"description\":\"Exploring the world through food, culture and familia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#organization\",\"name\":\"Growing Up Bilingual\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/GUB_logo2017_512x512.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/GUB_logo2017_512x512.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Growing Up Bilingual\"},\"image\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GrowUpBilingual\",\"https:\\\/\\\/x.com\\\/GrowUpBilingual\",\"https:\\\/\\\/www.instagram.com\\\/paulabendfeldt\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/paulabendfeldt\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#\\\/schema\\\/person\\\/38bc5392534f86f23648e73caa28f6ff\",\"name\":\"Paula Bendfeldt-Diaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g\",\"caption\":\"Paula Bendfeldt-Diaz\"},\"description\":\"Paula Bendfeldt-D\u00edaz is a Guatemalan travel writer, photographer, and founder of Growing Up Bilingual. After spending more than 15 years in the United States, she now lives in Guatemala and shares detailed travel guides, traditional Guatemalan recipes, and cultural insights based on a lifetime of firsthand experience. Through her writing, Paula helps travelers discover Guatemala beyond the typical tourist route with practical advice, local recommendations, and authentic experiences that connect visitors with the country\u2019s people, culture, and traditions. Planning a trip to Guatemala? Paula offers personalized Guatemala itinerary planning and trip consultation services tailored to your interests, travel style, and budget. Contact her at paula@growingupbilingual.com to learn more.\",\"sameAs\":[\"https:\\\/\\\/growingupbilingual.com\"],\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.","og_description":"Es dif\u00edcil de imaginar, pero un gran porcentaje de los estadounidenses no pueden obtener una tarjeta de cr\u00e9dito o un pr\u00e9stamo de un banco debido a que su calificaci\u00f3n crediticia es muy baja. Casi la mitad de las personas con una calificaci\u00f3n crediticia inferior a 680 son rechazadas cuando buscan nuevas l\u00edneas de cr\u00e9dito. Y ... Read more","og_url":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/","og_site_name":"Growing Up Bilingual","article_publisher":"https:\/\/www.facebook.com\/GrowUpBilingual","article_published_time":"2019-08-16T17:37:00+00:00","article_modified_time":"2019-08-16T19:14:04+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/i0.wp.com\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368.jpg?fit=1600%2C1600&ssl=1","type":"image\/jpeg"}],"author":"Paula Bendfeldt-Diaz","twitter_card":"summary_large_image","twitter_creator":"@GrowUpBilingual","twitter_site":"@GrowUpBilingual","twitter_misc":{"Escrito por":"Paula Bendfeldt-Diaz","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#article","isPartOf":{"@id":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/"},"author":{"name":"Paula Bendfeldt-Diaz","@id":"https:\/\/growingupbilingual.com\/es\/#\/schema\/person\/38bc5392534f86f23648e73caa28f6ff"},"headline":"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.","datePublished":"2019-08-16T17:37:00+00:00","dateModified":"2019-08-16T19:14:04+00:00","mainEntityOfPage":{"@id":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/"},"wordCount":814,"commentCount":2,"publisher":{"@id":"https:\/\/growingupbilingual.com\/es\/#organization"},"image":{"@id":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#primaryimage"},"thumbnailUrl":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368.jpg","articleSection":["Finance"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/","url":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/","name":"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber.","isPartOf":{"@id":"https:\/\/growingupbilingual.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#primaryimage"},"image":{"@id":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#primaryimage"},"thumbnailUrl":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368.jpg","datePublished":"2019-08-16T17:37:00+00:00","dateModified":"2019-08-16T19:14:04+00:00","breadcrumb":{"@id":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#primaryimage","url":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368.jpg","contentUrl":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368.jpg","width":1600,"height":1600,"caption":"Why This Matters To Me When I moved to the United States 11 years ago, I was forced to start from scratch with no credit history. My family lived paycheck to paycheck for years, always in fear of what would happen if an emergency occurred and we were faced with a big expense. With no savings to our name, a financial emergency \u2013 like damage to our home or the need to repair our only car \u2013 would have devastated us. This is the reality for many families and even more so for many Hispanics."},{"@type":"BreadcrumbList","@id":"https:\/\/growingupbilingual.com\/es\/considering-a-short-term-loan-consider-these-facts-first\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/growingupbilingual.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfEsta considerando un pr\u00e9stamo a corto plazo? Esto es lo que debe saber."}]},{"@type":"WebSite","@id":"https:\/\/growingupbilingual.com\/es\/#website","url":"https:\/\/growingupbilingual.com\/es\/","name":"Growing Up Bilingual","description":"Exploring the world through food, culture and familia.","publisher":{"@id":"https:\/\/growingupbilingual.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/growingupbilingual.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/growingupbilingual.com\/es\/#organization","name":"Growing Up Bilingual","url":"https:\/\/growingupbilingual.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/growingupbilingual.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/growingupbilingual.com\/wp-content\/uploads\/2017\/10\/GUB_logo2017_512x512.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i1.wp.com\/growingupbilingual.com\/wp-content\/uploads\/2017\/10\/GUB_logo2017_512x512.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Growing Up Bilingual"},"image":{"@id":"https:\/\/growingupbilingual.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GrowUpBilingual","https:\/\/x.com\/GrowUpBilingual","https:\/\/www.instagram.com\/paulabendfeldt\/","https:\/\/www.pinterest.com\/paulabendfeldt\/"]},{"@type":"Person","@id":"https:\/\/growingupbilingual.com\/es\/#\/schema\/person\/38bc5392534f86f23648e73caa28f6ff","name":"Paula Bendfeldt-Diaz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g","caption":"Paula Bendfeldt-Diaz"},"description":"Paula Bendfeldt-D\u00edaz is a Guatemalan travel writer, photographer, and founder of Growing Up Bilingual. After spending more than 15 years in the United States, she now lives in Guatemala and shares detailed travel guides, traditional Guatemalan recipes, and cultural insights based on a lifetime of firsthand experience. Through her writing, Paula helps travelers discover Guatemala beyond the typical tourist route with practical advice, local recommendations, and authentic experiences that connect visitors with the country\u2019s people, culture, and traditions. Planning a trip to Guatemala? Paula offers personalized Guatemala itinerary planning and trip consultation services tailored to your interests, travel style, and budget. Contact her at paula@growingupbilingual.com to learn more.","sameAs":["https:\/\/growingupbilingual.com"],"url":"https:\/\/growingupbilingual.com\/es\/author\/admin\/"}]}},"mv":{"thumbnail_id":40717,"thumbnail_uri":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2019\/08\/IMG_0368-300x300.jpg"},"_links":{"self":[{"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/posts\/40732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/comments?post=40732"}],"version-history":[{"count":0,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/posts\/40732\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/media\/40717"}],"wp:attachment":[{"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/media?parent=40732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/categories?post=40732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/tags?post=40732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}