{"id":61695,"date":"2023-12-01T10:07:43","date_gmt":"2023-12-01T15:07:43","guid":{"rendered":"https:\/\/growingupbilingual.com\/piloyada-antiguena-a-guatemalan-pork-and-bean-recipe\/"},"modified":"2024-02-16T13:30:13","modified_gmt":"2024-02-16T18:30:13","slug":"piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles","status":"publish","type":"post","link":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/","title":{"rendered":"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La receta de Piloyada Antigue\u00f1a es un platillo tradicional de Antigua Guatemala, conocido por su combinaci\u00f3n simple pero sabrosa de ingredientes. Esta receta de Piloyada re\u00fane el sabor \u00fanico de los frijoles piloy (similares a los frijoles rojos o pintos) con otros ingredientes frescos, creando una de mis recetas guatemaltecas favoritas con frijoles que es tanto nutritiva como deliciosa. En este plato tradicional guatemalteco, los frijoles piloy son la estrella. Se mezclan con ingredientes como chorizo, cerdo, verduras y un aderezo casero, haciendo de esta comida algo sustancioso y satisfactorio. Es un alimento b\u00e1sico en la cultura alimentaria guatemalteca, mostrando c\u00f3mo los ingredientes cotidianos pueden combinarse para crear algo especial.<\/span><\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#%C2%BFQue_es_la_Piloyada_Antiguena\" >\u00bfQu\u00e9 es la Piloyada Antigue\u00f1a?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#%C2%BFCuales_son_los_Ingredientes_de_la_Piloyada_Antiguena\" >\u00bfCu\u00e1les son los Ingredientes de la Piloyada Antigue\u00f1a?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#Origen_e_Historia_de_la_Receta_de_Piloyada_de_Antigua_Guatemala\" >Origen e&nbsp;Historia de la Receta de Piloyada de Antigua&nbsp;Guatemala&nbsp;<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#Receta_de_Piloyada_Antiguena\" >Receta de Piloyada Antigue\u00f1a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#Consejos_para_Preparar_la_Mejor_Piloyada\" >Consejos para Preparar la Mejor Piloyada:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#Como_Almacenar_Piloyada_Antiguena\" >C\u00f3mo Almacenar Piloyada Antigue\u00f1a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#Como_Servir_La_Piloyada\" >Como Servir La Piloyada<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#Otras_Recetas_Guatemaltecas\" >Otras Recetas Guatemaltecas<\/a><\/li><\/ul><\/nav><\/div>\n\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-61665 size-large\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-907x1024.jpg\" alt=\"Easy recipe for piloyada from Guatemala, facil receta de pilyada de Guatemala\" width=\"907\" height=\"1024\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-907x1024.jpg 907w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-266x300.jpg 266w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-768x867.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-1360x1536.jpg 1360w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-1813x2048.jpg 1813w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-560x632.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-150x169.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-735x830.jpg 735w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1.jpg 2048w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/p>\n<p>Yo crec\u00eden la Ciudad de Guatemala, y tengo lindos recuerdos de mis visitas a la hermosa ciudad colonial de Antigua Guatemala, los fines de semana con mi familia. Cada visita era una aventura, desde explorar sus coloridas calles hasta admirar la impresionante arquitectura. Pero lo que m\u00e1s me emocionaba siempre era la comida. Con su reconfortante mezcla de frijoles piloy y sabores vibrantes, este plato siempre me recuerda el calor y la alegr\u00eda de esas salidas familiares. Cada vez que pruebo la Piloyada Antigue\u00f1a, es como hacer un viaje de regreso a esos d\u00edas despreocupados, caminando por las calles empedradas de Antigua y disfrutando de la historia y deliciosa comida antigue\u00f1a.<\/p>\n<p>La Piloyada Antigue\u00f1a siempre ha tenido un lugar especial en mi coraz\u00f3n; es una de las mejores cosas para comer si visitas Antigua Guatemala.&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_la_Piloyada_Antiguena\"><\/span><b>\u00bfQu\u00e9 es la Piloyada Antigue\u00f1a?<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La Piloyada es un plato tradicional de Antigua, Guatemala, a base de frijoles y cerdo. El ingrediente principal de la piloyada son los frijoles piloy guatemaltecos, que pueden sustituirse por frijoles pintos o rojos, combinados con cerdo, chorizo y vegetales como tomate y cebolla. Es una deliciosa combinaci\u00f3n de una variedad de ingredientes muy chapines que crean una comida \u00fanica y deliciosa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-61667 size-large\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1996564505-2-1-894x1024.jpg\" alt=\"Best piloyada antigue\u00f1a recipe, la mejor receta de piloyada antigue\u00f1a\" width=\"894\" height=\"1024\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1996564505-2-1-894x1024.jpg 894w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1996564505-2-1-262x300.jpg 262w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1996564505-2-1-768x879.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1996564505-2-1-1341x1536.jpg 1341w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1996564505-2-1-1789x2048.jpg 1789w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1996564505-2-1-560x641.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1996564505-2-1-150x172.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1996564505-2-1.jpg 2048w\" sizes=\"auto, (max-width: 894px) 100vw, 894px\" \/><\/p>\n<p>Esta receta guatemalteca de frijoles es perfecta para cualquiera que busque probar comida aut\u00e9ntica guatemalteca. F\u00e1cil de hacer y llena de sabor, la Piloyada Antigue\u00f1a es una excelente manera de llevar un sabor de Guatemala a tu mesa.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFCuales_son_los_Ingredientes_de_la_Piloyada_Antiguena\"><\/span><b>\u00bfCu\u00e1les son los Ingredientes de la Piloyada Antigue\u00f1a?<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>El ingrediente clave en la Piloyada son los frijoles piloy, nativos de Guatemala. Los frijoles piloy (o frijoles rojos) son conocidos por su textura cremosa y su capacidad para absorber bien los sabores. Estos frijoles generalmente se cocinan con condimentos y luego se mezclan con otros ingredientes como huevos duros picados, queso fresco, chorizo, longaniza u otro tipo de salchicha, pimientos, cebollas y a veces otros vegetales o carnes, dependiendo de la receta o preferencia personal.<\/p>\n<p>El plato se adereza con una mezcla de aceite, vinagre y hierbas locales. La Piloyada a menudo se decora con queso y se sirve como plato principal o acompa\u00f1amiento en varias reuniones y celebraciones. Es un ejemplo perfecto de la fusi\u00f3n de influencias ind\u00edgenas y espa\u00f1olas en la cocina guatemalteca, mostrando la rica diversidad culinaria del pa\u00eds.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Origen_e_Historia_de_la_Receta_de_Piloyada_de_Antigua_Guatemala\"><\/span><b>Origen e&nbsp;Historia de la Receta de Piloyada de Antigua&nbsp;Guatemala&nbsp;<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La Piloyada, con su ingrediente central de frijoles piloy, es un plato profundamente arraigado en las tradiciones culinarias de Guatemala, especialmente en la regi\u00f3n de Antigua. La historia y el origen de los frijoles piloy y el plato de Piloyada reflejan un rico tapiz de patrimonio cultural y agr\u00edcola.<\/p>\n<p>Los frijoles piloy, tambi\u00e9n conocidos como \u00abfrijoles piloyes\u00bb, son una variedad de frijol nativa de Guatemala, son como un cruce entre frijoles rojos y pintos pero no son lo mismo. Son distintivos por su tama\u00f1o, color vibrante y patr\u00f3n, a menudo rojo o rosa con manchas. Estos frijoles han sido cultivados y utilizados en la cocina guatemalteca durante generaciones, formando una parte integral de la dieta local. Su sabor \u00fanico y textura cremosa los hacen un ingrediente favorito en varios platos tradicionales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-61657 size-large\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_101525128_XL-1024x683.jpg\" alt=\"Ingredients for Guatemalan piloyada antigue\u00f1a recipe\" width=\"1024\" height=\"683\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_101525128_XL-1024x683.jpg 1024w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_101525128_XL-300x200.jpg 300w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_101525128_XL-768x512.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_101525128_XL-1536x1024.jpg 1536w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_101525128_XL-560x373.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_101525128_XL-150x100.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_101525128_XL.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Los or\u00edgenes de la Piloyada se remontan a la \u00e9poca colonial en Guatemala. El plato representa una fusi\u00f3n de influencias culinarias espa\u00f1olas, ingredientes ind\u00edgenas guatemaltecos y m\u00e9todos de cocina. Mientras los espa\u00f1oles introdujeron nuevas t\u00e9cnicas de cocina e ingredientes como el aceite de oliva y el vinagre, los ind\u00edgenas aportaron alimentos b\u00e1sicos locales como los frijoles piloy y el ma\u00edz.<\/p>\n<p>Con el tiempo, la Piloyada evolucion\u00f3 en un plato que simboliza una mezcla de culturas. Este sustancioso plato de frijoles es una celebraci\u00f3n de los sabores y la historia guatemalteca. La combinaci\u00f3n de frijoles piloy con ingredientes como chorizo, huevos duros y vegetales es un testimonio de la diversa producci\u00f3n agr\u00edcola disponible en la regi\u00f3n.<\/p>\n<p>Hoy en d\u00eda, la Piloyada no es solo un plato popular en Antigua sino tambi\u00e9n parte de la identidad cultural de Guatemala. A menudo se sirve durante festivales y reuniones, mostrando el legado duradero de las influencias ind\u00edgenas y coloniales en la cocina guatemalteca. La continua popularidad de la Piloyada y el uso de frijoles piloy en la cocina guatemalteca son recordatorios de la rica historia agr\u00edcola y cultural de la regi\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-61663 size-large\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-e1701440454658.jpg\" alt=\"Piloyada Antigue\u00f1a recipe, receta de piloyada antigue\u00f1a\" width=\"1024\" height=\"835\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-e1701440454658.jpg 1669w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-e1701440454658-300x245.jpg 300w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-e1701440454658-1024x835.jpg 1024w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-e1701440454658-768x626.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-e1701440454658-1536x1253.jpg 1536w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-e1701440454658-560x457.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-e1701440454658-150x122.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-e1701440454658-735x599.jpg 735w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Receta_de_Piloyada_Antiguena\"><\/span><b>Receta de Piloyada Antigue\u00f1a<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><b>Ingredientes:<\/b><\/h3>\n<ul>\n<li>1 lb de frijoles piloy (pueden sustituirse por <a href=\"https:\/\/amzn.to\/4bR9HKq\" target=\"_blank\" rel=\"nofollow noopener\">frijoles rojos<\/a> o <a href=\"https:\/\/amzn.to\/4bECykY\">frijoles pintos<\/a>)<\/li>\n<li>1 hoja de laurel<\/li>\n<li>3 dientes de ajo, finamente picados<\/li>\n<li>1 ramita de tomillo fresco<\/li>\n<li>6 longanizas (o 3 salchichas kielbasa como sustituto de 6 longanizas)<\/li>\n<li>6 <a href=\"https:\/\/amzn.to\/3V15QVd\" target=\"_blank\" rel=\"nofollow noopener\">chorizos al estilo espa\u00f1ol<\/a>&nbsp;<\/li>\n<li>\u00bd lb de lomo de cerdo<\/li>\n<li>\u00bc taza de vinagre blanco o vinagre de manzana<\/li>\n<li>\u00bd lb de tomates, picados<\/li>\n<li>1 cebolla amarilla grande, picada<\/li>\n<li>1 ramita de perejil, finamente picada<\/li>\n<li>Sal y pimienta, al gusto<\/li>\n<li>Agua para cocinar<\/li>\n<li>Perejil fresco<\/li>\n<li>1 huevo cocido, rebanado<\/li>\n<li>\u00bc taza de Queso fresco,<\/li>\n<li>Queso duro, u otro queso mexicano desmenuzable<\/li>\n<\/ul>\n<h3><b>Instructions:<\/b><\/h3>\n<ul>\n<li><strong>Preparaci\u00f3n de los Frijoles: <\/strong>\n<ul>\n<li>Remoja los frijoles piloy durante la noche en agua para ablandarlos.&nbsp;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-61659 size-large\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_271430818_XL-1024x683.jpg\" alt=\"How to make Guatemalan piloyada\" width=\"1024\" height=\"683\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_271430818_XL-1024x683.jpg 1024w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_271430818_XL-300x200.jpg 300w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_271430818_XL-768x512.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_271430818_XL-1536x1024.jpg 1536w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_271430818_XL-560x373.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_271430818_XL-150x100.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/Depositphotos_271430818_XL.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<ul>\n<li aria-level=\"1\"><b>Cocinar los Frijoles:&nbsp;<\/b>\n<ul>\n<li aria-level=\"1\">Escurre los frijoles y trasl\u00e1dalos a una olla a presi\u00f3n.<\/li>\n<li aria-level=\"1\">Agrega la hoja de laurel, el ajo picado y el tomillo.<\/li>\n<li aria-level=\"1\">Cubre con agua y cocina a presi\u00f3n durante unos 30 minutos hasta que los frijoles est\u00e9n tiernos.<\/li>\n<\/ul>\n<\/li>\n<li><b>Preparaci\u00f3n del Lomo de Cerdo:<\/b>\n<ul>\n<li>Hierve el lomo de cerdo en 1 litro de agua hasta que est\u00e9 cocido, d\u00e9jalo enfriar y luego c\u00f3rtalo en trozos peque\u00f1os.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Cocina las Salchichas:<\/strong>\n<ul>\n<li>Cocina las salchichas longaniza (o salchichas kielbasa como sustituto) y el chorizo estilo espa\u00f1ol en una sart\u00e9n hasta que se doren.<\/li>\n<li>Una vez enfriadas, corta las salchichas en rodajas.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Combina los Ingredientes:<\/strong>\n<ul>\n<li>En un taz\u00f3n grande para mezclar, mezcla los frijoles cocidos (sin el agua), los trozos de lomo de cerdo y las rodajas de salchicha.<\/li>\n<\/ul>\n<\/li>\n<li><strong>A\u00f1ade Ingredientes Frescos y Aderezo:<\/strong>\n<ul>\n<li>A\u00f1ade los tomates picados, la cebolla picada y el perejil picado.<\/li>\n<li>Agrega el vinagre y sazona con sal y pimienta.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Toques Finales:<\/strong>\n<ul>\n<li>Mezcla bien todos los ingredientes.<\/li>\n<li>Opcionalmente, adorna con queso duro rallado, m\u00e1s perejil picado y rodajas de huevo duro.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Sugerencias para Servir:<\/strong>\n<ul>\n<li>Sirve la Piloyada Antigue\u00f1a caliente o a temperatura ambiente como plato principal o acompa\u00f1amiento.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Este plato es ideal para compartir con familiares y amigos. La Piloyada Antigue\u00f1a es m\u00e1s que una comida; es una experiencia culinaria que une a las personas y celebra la rica historia gastron\u00f3mica de Guatemala.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Consejos_para_Preparar_la_Mejor_Piloyada\"><\/span><b>Consejos para Preparar la Mejor Piloyada:<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Aseg\u00farate de remojar los frijoles durante la noche para reducir el tiempo de cocci\u00f3n y mejorar la digestibilidad.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Los frijoles deben cocinarse hasta quedar tiernos pero no deshechos. La textura es importante para la calidad general del plato.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Considera a\u00f1adir una hoja de laurel o un poco de comino a los frijoles mientras se cocinan para darles m\u00e1s sabor.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Mant\u00e9n un buen equilibrio entre los frijoles, los vegetales y el chorizo. Cada componente debe complementar a los dem\u00e1s sin dominarlos.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">El aderezo debe ser \u00e1cido y sabroso para contrastar con la riqueza de los frijoles y el chorizo.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Deja reposar la piloyada brevemente despu\u00e9s de mezclarla con el aderezo. Esto ayuda a que los sabores se fusionen.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">El huevo duro como guarnici\u00f3n a\u00f1ade un atractivo visual y una capa de textura y sabor. El cilantro fresco y el queso fresco hacen que este plato se vea y sepa estupendo.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">La Piloyada se puede servir caliente o a temperatura ambiente, seg\u00fan la preferencia.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-61661 size-large\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1-1024x944.jpg\" alt=\"Piloyada antigue\u00f1a recipe from Guatemala\" width=\"1024\" height=\"944\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1-1024x944.jpg 1024w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1-300x276.jpg 300w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1-768x708.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1-1536x1415.jpg 1536w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1-560x516.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1-150x138.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Como_Almacenar_Piloyada_Antiguena\"><\/span><b>C\u00f3mo Almacenar Piloyada Antigue\u00f1a<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Almacenar y congelar adecuadamente la Piloyada puede ayudar a mantener su sabor y textura, permiti\u00e9ndote disfrutarla m\u00e1s adelante. As\u00ed es como puedes hacerlo:<\/p>\n<h3><b>Almacenamiento en el Refrigerador:<\/b><\/h3>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Deja enfriar la Piloyada a temperatura ambiente despu\u00e9s de cocinar. Es importante no almacenar comida caliente directamente en el refrigerador, ya que puede elevar la temperatura dentro del mismo.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Transfiere la Piloyada a un recipiente herm\u00e9tico. Esto ayudar\u00e1 a mantenerla fresca y evitar\u00e1 que absorba otros olores del refrigerador.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Almacenada en el refrigerador, la Piloyada puede durar unos 3 a 5 d\u00edas.<\/li>\n<\/ul>\n<h3><b>Como&nbsp;Congelar la Piloyada:<\/b><\/h3>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Aseg\u00farate de que la Piloyada est\u00e9 completamente fr\u00eda antes de congelarla.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Si tienes una gran cantidad, considera dividirla en porciones m\u00e1s peque\u00f1as. Esto facilita descongelar solo lo que necesitas m\u00e1s adelante.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Usa bolsas o recipientes aptos para congelador para almacenar la Piloyada. Elimina la mayor cantidad de aire posible de las bolsas para prevenir la quemadura por congelaci\u00f3n.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Etiqueta las bolsas o recipientes con la fecha para saber cu\u00e1ndo lo congelaste.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">La Piloyada se puede congelar hasta por 2-3 meses. Despu\u00e9s de esto, puede empezar a perder su calidad.<\/li>\n<\/ul>\n<h4><b>Como&nbsp;Descongelarla y Recalentarla:<\/b><\/h4>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Descongela la Piloyada congelada en el refrigerador durante la noche. Para un m\u00e9todo m\u00e1s r\u00e1pido, puedes usar el microondas, pero aseg\u00farate de usar un recipiente apto para microondas.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Recalienta la Piloyada en el microondas o en la estufa. Agrega un poco de agua o caldo para humedecerla si parece seca.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Revu\u00e9lvela bien mientras se recalienta para asegurar que se caliente de manera uniforme.<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\"><strong>Nota:<\/strong> Ten cuidad al congelar Piloyada con ciertos ingredientes. Los platos con huevos duros y vegetales frescos podr\u00edan no congelarse tan bien, ya que estos ingredientes pueden cambiar de textura cuando se congelan y luego se descongelan. Si planeas congelar la Piloyada, podr\u00eda ser mejor agregar estos ingredientes frescos cuando est\u00e9s listo para servir.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Como_Servir_La_Piloyada\"><\/span><strong>Como Servir La Piloyada<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Para una experiencia m\u00e1s aut\u00e9ntica, sirve la Piloyada Antigue\u00f1a con una guarnici\u00f3n de tortillas reci\u00e9n hechas o pan tradicional guatemalteco. Tambi\u00e9n puedes acompa\u00f1arla con una bebida local refrescante como horchata o tamarindo. La Piloyada Antigue\u00f1a es un plato que refleja la diversidad y riqueza de la cocina guatemalteca. Al preparar y disfrutar esta receta, no solo est\u00e1s saboreando un delicioso plato, sino tambi\u00e9n experimentando una parte integral de la cultura guatemalteca. As\u00ed que, \u00a1an\u00edmate a hacer esta receta antigue\u00f1a en tu pr\u00f3xima reuni\u00f3n familiar o con amigos!<\/p>\n<script type=\"application\/ld+json\">{\"@context\":\"http:\\\/\\\/schema.org\",\"@type\":\"Recipe\",\"name\":\"Piloyada Antigue\\u00f1a: Receta Guatemalteca de Cerdo y Frijoles\",\"author\":{\"@type\":\"Person\",\"name\":\"Paula Bendfeldt-Diaz\"},\"datePublished\":\"2024-02-16\",\"recipeYield\":10,\"image\":[\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/shutterstock_1937410027-2-1-720x720.jpg\",\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/shutterstock_1937410027-2-1-720x540.jpg\",\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/shutterstock_1937410027-2-1-540x720.jpg\",\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/shutterstock_1937410027-2-1-720x405.jpg\",\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/shutterstock_1937410027-2-1-735x830.jpg\"],\"prepTime\":\"PT20M\",\"cookTime\":\"PT45M\",\"performTime\":\"PT45M\",\"totalTime\":\"PT1H5M\",\"recipeIngredient\":[\"1 lb de frijoles piloy (se pueden sustituir por frijoles rojos o frijoles pintos)\",\"1 hoja de laurel\",\"3 dientes de ajo, finamente picados\",\"1 ramita de tomillo fresco\",\"6 salchichas longaniza (o 3 salchichas kielbasa como sustituto de 6 longanizas)\",\"6 salchichas chorizo estilo espa\\u00f1ol\",\"\\u00bd lb de lomo de cerdo\",\"\\u00bc taza de vinagre blanco o vinagre de manzana\",\"\\u00bd lb de tomates, picados\",\"1 cebolla amarilla grande, picada\",\"Sal y pimienta, al gusto\",\"1 ramita de perejil, finamente picada\",\"1 huevo duro, rebanado\",\"\\u00bc taza de queso fresco, queso duro, u otro tipo de queso mexicano desmenuzable\"],\"recipeInstructions\":[{\"@type\":\"HowToStep\",\"text\":\"Remoja los frijoles piloy durante la noche en agua para ablandarlos.\",\"position\":1,\"name\":\"Remoja los frijoles piloy durante la noche en...\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_1\"},{\"@type\":\"HowToStep\",\"text\":\"Escurre los frijoles y transfi\\u00e9relos a una olla a presi\\u00f3n.\",\"position\":2,\"name\":\"Escurre los frijoles y transfi\\u00e9relos a una olla...\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_2\"},{\"@type\":\"HowToStep\",\"text\":\"Agrega la hoja de laurel, el ajo picado y el tomillo.\",\"position\":3,\"name\":\"Agrega la hoja de laurel, el ajo picado...\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_3\"},{\"@type\":\"HowToStep\",\"text\":\"Cubre con agua y cocina a presi\\u00f3n durante unos 30 minutos hasta que los frijoles est\\u00e9n tiernos.\",\"position\":4,\"name\":\"Cubre con agua y cocina a presi\\u00f3n durante...\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_4\"},{\"@type\":\"HowToStep\",\"text\":\"Mientras se cocinan los frijoles, hierve el lomo de cerdo en 1 litro de agua hasta que est\\u00e9 cocido, d\\u00e9jalo enfriar y luego c\\u00f3rtalo en trozos peque\\u00f1os.\",\"position\":5,\"name\":\"Mientras se cocinan los frijoles, hierve el lomo...\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_5\"},{\"@type\":\"HowToStep\",\"text\":\"Cocina las salchichas longaniza (o salchichas kielbasa como sustituto) y el chorizo estilo espa\\u00f1ol en una sart\\u00e9n hasta que se doren.\",\"position\":6,\"name\":\"Cocina las salchichas longaniza (o salchichas kielbasa como...\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_6\"},{\"@type\":\"HowToStep\",\"text\":\"Una vez enfriadas, corta las salchichas en rodajas.\",\"position\":7,\"name\":\"Una vez enfriadas, corta las salchichas en rodajas.\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_7\"},{\"@type\":\"HowToStep\",\"text\":\"En un taz\\u00f3n grande, mezcla los frijoles cocidos (sin el agua), los trozos de lomo de cerdo y las rodajas de salchicha.\",\"position\":8,\"name\":\"En un taz\\u00f3n grande, mezcla los frijoles cocidos...\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_8\"},{\"@type\":\"HowToStep\",\"text\":\"A\\u00f1ade los tomates picados, la cebolla picada y el perejil picado al taz\\u00f3n.\",\"position\":9,\"name\":\"A\\u00f1ade los tomates picados, la cebolla picada y...\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_9\"},{\"@type\":\"HowToStep\",\"text\":\"Vierte el vinagre y sazona con sal y pimienta.\",\"position\":10,\"name\":\"Vierte el vinagre y sazona con sal y...\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_10\"},{\"@type\":\"HowToStep\",\"text\":\"Mezcla bien todos los ingredientes.\",\"position\":11,\"name\":\"Mezcla bien todos los ingredientes.\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_11\"},{\"@type\":\"HowToStep\",\"text\":\"Opcionalmente, adorna con queso duro rallado, el perejil picado y rebanadas de huevo duro.\",\"position\":12,\"name\":\"Opcionalmente, adorna con queso duro rallado, el perejil...\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#mv_create_247_12\"}],\"nutrition\":{\"@type\":\"NutritionInformation\",\"calories\":\"448 calories\",\"carbohydrateContent\":\"17 grams carbohydrates\",\"cholesterolContent\":\"109 milligrams cholesterol\",\"fatContent\":\"31 grams fat\",\"fiberContent\":\"3 grams fiber\",\"proteinContent\":\"26 grams protein\",\"saturatedFatContent\":\"11 grams saturated fat\",\"servingSize\":\"1 taza\",\"sodiumContent\":\"1111 milligrams sodium\",\"sugarContent\":\"7 grams sugar\",\"transFatContent\":\"0 grams trans fat\",\"unsaturatedFatContent\":\"16 grams unsaturated fat\"},\"aggregateRating\":{\"@type\":\"AggregateRating\",\"ratingValue\":5,\"reviewCount\":\"1\"},\"review\":[{\"@type\":\"Review\",\"author\":{\"@type\":\"Person\",\"name\":\"Andrea\"},\"datePublished\":\"2025-12-19T04:54:06+00:00\",\"reviewRating\":{\"@type\":\"Rating\",\"ratingValue\":\"5.0\",\"bestRating\":\"5\",\"worstRating\":\"1\"},\"reviewBody\":\"Loved how this turned out\",\"name\":\"Great recipe!\"}],\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/\"}<\/script>\t<section id=\"mv-creation-247\" class=\"mv-create-card mv-create-card-247 mv-recipe-card mv-create-card-style-centered-dark mv-no-js mv-create-center-cards mv-create-has-uppercase mv-create-has-image \" style=\"position: relative;\">\n\t\t\n\t\t<div class=\"mv-create-wrapper\">\n\n\t\t\t\n\t\t\t<header class=\"mv-create-header\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-720x720.jpg\" class=\"mv-create-image no_pin ggnoads\" data-pin-nopin=\"true\" alt=\"Easy recipe for piloyada from Guatemala, facil receta de pilyada de Guatemala\" width=\"720\" height=\"720\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-720x720.jpg 720w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-150x150.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-500x500.jpg 500w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-96x96.jpg 96w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-200x200.jpg 200w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-320x320.jpg 320w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-480x480.jpg 480w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" data-pin-media=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1.jpg\"><div class=\"mv-pinterest-btn mv-pinterest-btn-right\" data-mv-pinterest-desc=\"Piloyada%20Antigue%C3%B1a%3A%20Receta%20Guatemalteca%20de%20Cerdo%20y%20Frijoles\" data-mv-pinterest-img-src=\"https%3A%2F%2Fgrowingupbilingual.com%2Fwp-content%2Fuploads%2F2023%2F12%2Fshutterstock_1937410027-2-1.jpg\" data-mv-pinterest-url=\"https%3A%2F%2Fgrowingupbilingual.com%2Fes%2Fpiloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles%2F\"><\/div>\n<h1 class=\"mv-create-title mv-create-title-primary\">Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles<\/h1>\n\n<div class=\"mv-create-times mv-create-times-3\">\n\n\t\t\t\t<div class=\"mv-create-time mv-create-time-yield\">\n\t\t\t\t<em class=\"mv-create-time-label mv-create-lowercase mv-create-strong\">Yield: <\/em>\n\t\t\t\t<span class=\"mv-create-time-format mv-create-uppercase\">10 porciones de 1 taza<\/span>\n\t\t\t<\/div>\n\t\n\t\t\t\t\t\t<div class=\"mv-create-time mv-create-time-prep\">\n\t\t\t\t<em class=\"mv-create-time-label mv-create-lowercase mv-create-strong\">Prep Time: <\/em>\n\t\t\t\t<span class=\"mv-create-time-format mv-create-uppercase\"><span class=\"mv-time-part mv-time-minutes\">20 minutes<\/span> <\/span>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mv-create-time mv-create-time-active\">\n\t\t\t\t<em class=\"mv-create-time-label mv-create-lowercase mv-create-strong\">Cook Time: <\/em>\n\t\t\t\t<span class=\"mv-create-time-format mv-create-uppercase\"><span class=\"mv-time-part mv-time-minutes\">45 minutes<\/span> <\/span>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"mv-create-time mv-create-time-total\">\n\t\t\t\t<em class=\"mv-create-time-label mv-create-lowercase mv-create-strong\">Total Time: <\/em>\n\t\t\t\t<span class=\"mv-create-time-format mv-create-uppercase\"><span class=\"mv-time-part mv-time-hours\">1 hour<\/span> <span class=\"mv-time-part mv-time-minutes\">5 minutes<\/span> <\/span>\n\t\t\t<\/div>\n\t\t\t\n<\/div>\n\t<div id=\"mv-create-247\" class=\"mv-create-reviews\" data-mv-create-id=\"247\" data-mv-create-rating=\"5\" data-mv-create-total-ratings=\"1\" data-mv-rest-url=\"https:\/\/growingupbilingual.com\/es\/wp-json\/\"><\/div>\n\t<!-- This is a button so it inherits theme styles -->\n\t<form class=\"mv-create-print-form\" method=\"get\" target=\"_blank\" action=\"https:\/\/growingupbilingual.com\/es\/wp-json\/mv-create\/v1\/creations\/247\/print\"><button class=\"mv-create-button mv-create-print-button\" data-mv-print=\"https:\/\/growingupbilingual.com\/es\/wp-json\/mv-create\/v1\/creations\/247\/print\">Print<\/button><\/form>\n\t\t\t<\/header>\n\n\t\t\t<div class=\"mv-create-target mv-create-primary-unit\"><div class=\"mv_slot_target\" data-slot=\"recipe\"><\/div><\/div>\t<div class=\"mv-create-ingredients\">\n\t\t<h2 class=\"mv-create-ingredients-title mv-create-title-secondary\">Ingredients<\/h2>\n\n\t\t\t\t\t\t\t\t<div class=\"mv-create-ingredient-group\" data-ingredient-group=\"0\">\n\t\t\t\t\t\t\t\t<ul class=\"mv-create-ingredient-list\">\n\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"0\" data-ingredient-id=\"46768\">\n\t\t\t\t\t\t\t1 lb de frijoles piloy (se pueden sustituir por frijoles rojos o frijoles pintos)\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"1\" data-ingredient-id=\"46769\">\n\t\t\t\t\t\t\t1 hoja de laurel\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"2\" data-ingredient-id=\"46770\">\n\t\t\t\t\t\t\t3 dientes de ajo, finamente picados\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"3\" data-ingredient-id=\"46771\">\n\t\t\t\t\t\t\t1 ramita de tomillo fresco\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"4\" data-ingredient-id=\"46772\">\n\t\t\t\t\t\t\t6 salchichas longaniza (o 3 salchichas kielbasa como sustituto de 6 longanizas)\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"5\" data-ingredient-id=\"46773\">\n\t\t\t\t\t\t\t6 salchichas chorizo estilo espa\u00f1ol\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"6\" data-ingredient-id=\"46774\">\n\t\t\t\t\t\t\t\u00bd lb de lomo de cerdo\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"7\" data-ingredient-id=\"46775\">\n\t\t\t\t\t\t\t\u00bc taza de vinagre blanco o vinagre de manzana\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"8\" data-ingredient-id=\"46776\">\n\t\t\t\t\t\t\t\u00bd lb de tomates, picados\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"9\" data-ingredient-id=\"46777\">\n\t\t\t\t\t\t\t1 cebolla amarilla grande, picada\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"10\" data-ingredient-id=\"46778\">\n\t\t\t\t\t\t\tSal y pimienta, al gusto\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"11\" data-ingredient-id=\"46779\">\n\t\t\t\t\t\t\t1 ramita de perejil, finamente picada\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"12\" data-ingredient-id=\"46780\">\n\t\t\t\t\t\t\t1 huevo duro, rebanado\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t<li data-ingredient-index=\"13\" data-ingredient-id=\"46781\">\n\t\t\t\t\t\t\t\u00bc taza de queso fresco, queso duro, u otro tipo de queso mexicano desmenuzable\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"mv-create-hands-free\"><\/div>\n\t\t<div class=\"mv-create-instructions mv-create-instructions-slot-v2\">\n\t\t<h2 class=\"mv-create-instructions-title mv-create-title-secondary\">Instructions<\/h2>\n\t\t<ol><ol><li data-step-index=\"0\" id=\"mv_create_247_1\">Remoja los frijoles piloy durante la noche en agua para ablandarlos.<\/li><li data-step-index=\"1\" id=\"mv_create_247_2\">Escurre los frijoles y transfi\u00e9relos a una olla a presi\u00f3n.<\/li><li data-step-index=\"2\" id=\"mv_create_247_3\">Agrega la hoja de laurel, el ajo picado y el tomillo.<\/li><li data-step-index=\"3\" id=\"mv_create_247_4\">Cubre con agua y cocina a presi\u00f3n durante unos 30 minutos hasta que los frijoles est\u00e9n tiernos.<\/li><li data-step-index=\"4\" id=\"mv_create_247_5\">Mientras se cocinan los frijoles, hierve el lomo de cerdo en 1 litro de agua hasta que est\u00e9 cocido, d\u00e9jalo enfriar y luego c\u00f3rtalo en trozos peque\u00f1os.<\/li><li data-step-index=\"5\" id=\"mv_create_247_6\">Cocina las salchichas longaniza (o salchichas kielbasa como sustituto) y el chorizo estilo espa\u00f1ol en una sart\u00e9n hasta que se doren.<\/li><li data-step-index=\"6\" id=\"mv_create_247_7\">Una vez enfriadas, corta las salchichas en rodajas.<\/li><li data-step-index=\"7\" id=\"mv_create_247_8\">En un taz\u00f3n grande, mezcla los frijoles cocidos (sin el agua), los trozos de lomo de cerdo y las rodajas de salchicha.<\/li><li data-step-index=\"8\" id=\"mv_create_247_9\">A\u00f1ade los tomates picados, la cebolla picada y el perejil picado al taz\u00f3n.<\/li><li data-step-index=\"9\" id=\"mv_create_247_10\">Vierte el vinagre y sazona con sal y pimienta.<\/li><li data-step-index=\"10\" id=\"mv_create_247_11\">Mezcla bien todos los ingredientes.<\/li><li data-step-index=\"11\" id=\"mv_create_247_12\">Opcionalmente, adorna con queso duro rallado, el perejil picado y rebanadas de huevo duro.<\/li><\/ol><\/ol>\t<\/div>\n\t<div class=\"mv-create-notes mv-create-notes-slot-v2\">\n\t\t<h2 class=\"mv-create-notes-title mv-create-title-secondary\">Notes<\/h2>\n\t\t<div class=\"mv-create-notes-content\">\n\t\t\t<p><p>Sugerencias para servir: Sirve la Piloyada Antigue\u00f1a caliente o a temperatura ambiente como plato principal o acompa\u00f1amiento.<\/p><\/p>\n\t\t<\/div>\n\t<\/div>\n<div class=\"mv-create-nutrition\">\n\n\t<div class=\"mv-create-nutrition-box\">\n\n\t\t<h6 class=\"mv-create-nutrition-title mv-create-strong\"><span>Nutrition Information:<\/span><\/h6>\n\n\t\t\n\t\t\t\t\t<span class=\"mv-create-nutrition-item mv-create-nutrition-serving-size\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Serving Size:<\/span> 1 taza<\/span>\n\t\t\n\t\t<br><span class=\"mv-create-nutrition-amount\"><em>Amount Per Serving:<\/em><\/span>\n\n\t\t<span class=\"mv-create-nutrition-item mv-create-nutrition-calories\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Calories:<\/span> 448<\/span><span class=\"mv-create-nutrition-item mv-create-nutrition-total-fat\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Total Fat:<\/span> 31g<\/span><span class=\"mv-create-nutrition-item mv-create-nutrition-saturated-fat mv-create-nutrition-indent\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Saturated Fat:<\/span> 11g<\/span><span class=\"mv-create-nutrition-item mv-create-nutrition-trans-fat mv-create-nutrition-indent\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Trans Fat:<\/span> 0g<\/span><span class=\"mv-create-nutrition-item mv-create-nutrition-unsaturated-fat mv-create-nutrition-indent\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Unsaturated Fat:<\/span> 16g<\/span><span class=\"mv-create-nutrition-item mv-create-nutrition-cholesterol\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Cholesterol:<\/span> 109mg<\/span><span class=\"mv-create-nutrition-item mv-create-nutrition-sodium\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Sodium:<\/span> 1111mg<\/span><span class=\"mv-create-nutrition-item mv-create-nutrition-carbohydrates\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Carbohydrates:<\/span> 17g<\/span><span class=\"mv-create-nutrition-item mv-create-nutrition-fiber mv-create-nutrition-indent\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Fiber:<\/span> 3g<\/span><span class=\"mv-create-nutrition-item mv-create-nutrition-sugar mv-create-nutrition-indent\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Sugar:<\/span> 7g<\/span><span class=\"mv-create-nutrition-item mv-create-nutrition-protein\"><span class=\"mv-create-nutrition-label mv-create-uppercase\">Protein:<\/span> 26g<\/span>\n\t<\/div>\n\n\t\n<\/div>\n\n\n\t<div class=\"mv-create-social\">\n\t\t<div class=\"mv-create-social-icon mv-create-social-icon-pinterest\">\n\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 26 26\" width=\"26px\" height=\"26px\" class=\"svg svg-pinterest\">\n\t\t<path d=\"M 13 0.1875 C 5.925781 0.1875 0.1875 5.925781 0.1875 13 C 0.1875 18.421875 3.558594 23.046875 8.316406 24.917969 C 8.296875 24.480469 8.296875 22.210938 9.875 15.441406 C 10.085938 13.183594 9.792969 12.382813 9.792969 11.445313 C 9.792969 9.316406 10.898438 8.867188 11.546875 8.867188 C 12.46875 8.867188 13.738281 9.21875 13.738281 10.703125 C 13.738281 12.402344 12.351563 12.851563 12.351563 12.851563 C 12.351563 12.851563 12.253906 13.285156 12.136719 14.492188 C 12.023438 15.703125 12.507813 17.015625 14.480469 17.015625 C 17.644531 17.015625 18.132813 12.621094 18.132813 11.410156 C 18.132813 9.742188 16.910156 6.351563 13.109375 6.351563 C 8.042969 6.351563 7.171875 10.890625 7.171875 12.101563 C 7.171875 12.621094 7.3125 13.535156 7.410156 13.925781 C 8.367188 14.082031 8.269531 15.390625 7.859375 15.761719 C 7.40625 16.171875 5.066406 16.660156 5.066406 11.527344 C 5.066406 6.640625 9.421875 4.121094 13.246094 4.121094 C 16.886719 4.121094 20.847656 6.632813 20.847656 11.46875 C 20.847656 15.789063 17.746094 19.1875 14.484375 19.1875 C 12.527344 19.1875 11.488281 17.574219 11.488281 17.574219 C 11.488281 19.085938 8.714844 24.273438 8.359375 24.933594 C 9.800781 25.492188 11.363281 25.8125 13 25.8125 C 20.078125 25.8125 25.8125 20.078125 25.8125 13 C 25.8125 5.921875 20.074219 0.1875 13 0.1875 Z \" \/>\n\t<\/svg>\n<\/div>\n\t\t<div class=\"mv-create-social-content\">\n\t\t\t<h2 class=\"mv-create-social-title mv-create-title-secondary\">Did you make this recipe?<\/h2>\n\t\t\t<p class=\"mv-create-social-body\">Please leave a comment on the blog or share a photo on Pinterest<\/a><\/p>\n\t\t<\/div>\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t<footer class=\"mv-create-footer\">\n\t\t\t\n<div class=\"mv-create-footer-flexbox\">\n\n\t\t\t<div class=\"mv-create-copy\">&copy; Paula Bendfeldt-Diaz<\/div>\t\n\t<div class=\"mv-create-categories\">\n\n\t\t\n\t\t\n\t<\/div>\n\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-735x830.jpg\" alt=\"\" data-pin-description=\"\" class=\"mv-create-pinterest no_pin ggnoads\" width=\"735\" height=\"830\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-735x830.jpg 735w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-266x300.jpg 266w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-907x1024.jpg 907w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-768x867.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-1360x1536.jpg 1360w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-1813x2048.jpg 1813w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-560x632.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1-150x169.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1.jpg 2048w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" data-pin-media=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-2-1.jpg\">\n<\/div>\n\t\t<\/footer>\n\n\t\t\n\t\t\t\t<div class=\"mv-create-checklists\" data-creation-id=\"247\"><\/div>\n\t\t\n\t<\/section>\n\n\t\n<h2><span class=\"ez-toc-section\" id=\"Otras_Recetas_Guatemaltecas\"><\/span><strong>Otras Recetas Guatemaltecas<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Aqu\u00ed tienes algunas otras recetas guatemaltecas sustanciosas que podr\u00edas disfrutar, y aseg\u00farate de revisar mi gu\u00eda completa sobre la comida guatemalteca, donde encontrar\u00e1s una lista completa de recetas guatemaltecas, desde <a href=\"https:\/\/growingupbilingual.com\/es\/la-mejor-receta-de-tamales-colorados-guatemaltecos\/\">tamales colorados<\/a> y guisos como el <a href=\"https:\/\/growingupbilingual.com\/es\/receta-guatemalteca-pollo-en-jocon\/\">Joc\u00f3n<\/a> hasta bebidas como la <a href=\"https:\/\/growingupbilingual.com\/es\/la-mejor-receta-de-rosa-de-jamaica\/\">rosa de jamaica<\/a> y los mejores postres guatemaltecos, incluyendo todo, desde <a href=\"https:\/\/growingupbilingual.com\/es\/rellenitos-de-platano\/\">rellenitos<\/a> hasta <a href=\"https:\/\/growingupbilingual.com\/es\/receta-de-bunuelos-guatemaltecos\/\">bu\u00f1uelos<\/a>.<\/p>\n<h3><a href=\"https:\/\/growingupbilingual.com\/es\/kakik-una-deliciosa-sopa-de-pavo-guatemalteca\/\"><strong>Sopa de Pavo Kak\u2019ik<\/strong><\/a><\/h3>\n<p>Esta sopa guatemalteca est\u00e1 llena de sabor, con pavo jugoso, especias y vegetales. El pavo es el ingrediente principal en este plato tradicional, pero el caldo le da su sabor inolvidable. El caldo se prepara mezclando chiles secos, tomates, tomatillos, ajo, cilantro y menta para crear una salsa rica y fragante que equilibra perfectamente el tierno pavo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-56648 size-large\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/02\/shutterstock_2034124028-2-716x1024.jpg\" alt=\"&quot;Kak ik&quot; traditional Guatemalan dish, made with turkey, tomato and many aromatic herbs, served with white rice and small tamales.\" width=\"716\" height=\"1024\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/02\/shutterstock_2034124028-2-716x1024.jpg 716w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/02\/shutterstock_2034124028-2-210x300.jpg 210w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/02\/shutterstock_2034124028-2-768x1099.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/02\/shutterstock_2034124028-2-1073x1536.jpg 1073w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/02\/shutterstock_2034124028-2-1431x2048.jpg 1431w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/02\/shutterstock_2034124028-2-560x801.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/02\/shutterstock_2034124028-2-600x859.jpg 600w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/02\/shutterstock_2034124028-2-150x215.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/02\/shutterstock_2034124028-2.jpg 1568w\" sizes=\"auto, (max-width: 716px) 100vw, 716px\" \/><\/p>\n<h3><a href=\"https:\/\/growingupbilingual.com\/es\/receta-guatemalteca-pepian-de-pollo\/\"><strong>Pepi\u00e1n De Pollo<\/strong><\/a><\/h3>\n<p>El pepi\u00e1n de pollo es una de las recetas guatemaltecas m\u00e1s antiguas. Este estofado de pollo es rico en sabores y especias tostadas. Puedes prepararlo con pollo, carne de res o cerdo (o una combinaci\u00f3n de todos). Se guisa la carne en una salsa a base de tomate con semillas y pimientos tostados. Agregar papas y zanahorias, con arroz blanco como acompa\u00f1amiento, hace de esta receta una comida completa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-50721 size-large\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1846035454-2-777x1024.jpg\" alt=\"Chicken pepian from Guatemala\" width=\"777\" height=\"1024\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1846035454-2-777x1024.jpg 777w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1846035454-2-228x300.jpg 228w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1846035454-2-768x1012.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1846035454-2-1166x1536.jpg 1166w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1846035454-2-1554x2048.jpg 1554w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1846035454-2-560x738.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1846035454-2-150x198.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1846035454-2-scaled-735x968.jpg 735w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1846035454-2-scaled.jpg 1943w\" sizes=\"auto, (max-width: 777px) 100vw, 777px\" \/><\/p>\n<h3><a href=\"https:\/\/growingupbilingual.com\/es\/receta-de-subanik-un-delicioso-guiso-guatemalteco\/\"><strong>Subanik<\/strong><\/a><\/h3>\n<p>El Subanik es un guiso tradicional guatemalteco muy querido por su sabor rico y contundente. Se prepara con tres tipos diferentes de carne cocida a fuego lento en un guiso de tomate especiado y dulce con chiles. Luego, el guiso se sazona con cebollas, ajo y hierbas y se espesa con harina de ma\u00edz o masa. Tradicionalmente, el Subanik se envuelve en una hoja de mashan, se ata con una cuerda de Cibaque y se cocina al vapor a la perfecci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-56367 size-large\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/01\/shutterstock_1738877948-2-1-909x1024.jpg\" alt=\"Guatemalan recipe for Subanik\" width=\"909\" height=\"1024\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/01\/shutterstock_1738877948-2-1-909x1024.jpg 909w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/01\/shutterstock_1738877948-2-1-266x300.jpg 266w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/01\/shutterstock_1738877948-2-1-768x865.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/01\/shutterstock_1738877948-2-1-1364x1536.jpg 1364w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/01\/shutterstock_1738877948-2-1-1818x2048.jpg 1818w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/01\/shutterstock_1738877948-2-1-560x631.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/01\/shutterstock_1738877948-2-1-600x676.jpg 600w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/01\/shutterstock_1738877948-2-1-150x169.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/01\/shutterstock_1738877948-2-1.jpg 2048w\" sizes=\"auto, (max-width: 909px) 100vw, 909px\" \/><\/p>\n<h3><a href=\"https:\/\/growingupbilingual.com\/es\/chuchitos-una-receta-tradicional-de-tamales-guatemaltecos\/\"><strong>Chuchitos<\/strong><\/a><\/h3>\n<p>Junto con los legendarios tamales colorados, los chuchitos son algunos de los tamales guatemaltecos m\u00e1s famosos. Son peque\u00f1os tamales rellenos de cerdo o pollo y un recado a base de tomate. S\u00edrvelos con frijoles negros refritos y el cl\u00e1sico \u00abPan Franc\u00e9s\u00bb guatemalteco, \u00a1y a disfrutar! \u00a1Consulta mi lista completa de tamales guatemaltecos aqu\u00ed!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-50755 size-large\" src=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1830356603-1024x683.jpg\" alt=\"best Guatemalan Chuchitos recipe\" width=\"1024\" height=\"683\" srcset=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1830356603-1024x683.jpg 1024w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1830356603-300x200.jpg 300w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1830356603-768x512.jpg 768w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1830356603-1536x1024.jpg 1536w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1830356603-560x373.jpg 560w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1830356603-150x100.jpg 150w, https:\/\/growingupbilingual.com\/wp-content\/uploads\/2021\/09\/shutterstock_1830356603.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<div class=\"mceTemp\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La receta de Piloyada Antigue\u00f1a es un platillo tradicional de Antigua Guatemala, conocido por su combinaci\u00f3n simple pero sabrosa de ingredientes. Esta receta de Piloyada re\u00fane el sabor \u00fanico de los frijoles piloy (similares a los frijoles rojos o pintos) con otros ingredientes frescos, creando una de mis recetas guatemaltecas favoritas con frijoles que es &#8230; <a title=\"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles\" class=\"read-more\" href=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/\" aria-label=\"Leer m\u00e1s sobre Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":61662,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"disable-jtr":false,"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","footnotes":""},"categories":[3007,6621],"tags":[7174,7072,7175,3014],"class_list":["post-61695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food-recipes-es","category-guatemalan-recipes-es","tag-bean-recipe-es","tag-guatemalan-recipe-es","tag-pork-recipe-es","tag-recipes-es","infinite-scroll-item","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles<\/title>\n<meta name=\"description\" content=\"This easy recipe for piloyada antigue\u00f1a, a bean and pork dish, is a delicious and hearty traditional Guatemalan dish that you will love.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles\" \/>\n<meta property=\"og:description\" content=\"This easy recipe for piloyada antigue\u00f1a, a bean and pork dish, is a delicious and hearty traditional Guatemalan dish that you will love.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/\" \/>\n<meta property=\"og:site_name\" content=\"Growing Up Bilingual\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GrowUpBilingual\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-01T15:07:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-16T18:30:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paula Bendfeldt-Diaz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GrowUpBilingual\" \/>\n<meta name=\"twitter:site\" content=\"@GrowUpBilingual\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paula Bendfeldt-Diaz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/\"},\"author\":{\"name\":\"Paula Bendfeldt-Diaz\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#\\\/schema\\\/person\\\/38bc5392534f86f23648e73caa28f6ff\"},\"headline\":\"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles\",\"datePublished\":\"2023-12-01T15:07:43+00:00\",\"dateModified\":\"2024-02-16T18:30:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/\"},\"wordCount\":2223,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/shutterstock_1937410027-1.jpg\",\"keywords\":[\"bean recipe\",\"Guatemalan recipe\",\"pork recipe\",\"recipes @es\"],\"articleSection\":[\"Food &amp; Recipes\",\"Guatemalan recipes\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/\",\"name\":\"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/shutterstock_1937410027-1.jpg\",\"datePublished\":\"2023-12-01T15:07:43+00:00\",\"dateModified\":\"2024-02-16T18:30:13+00:00\",\"description\":\"This easy recipe for piloyada antigue\u00f1a, a bean and pork dish, is a delicious and hearty traditional Guatemalan dish that you will love.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/shutterstock_1937410027-1.jpg\",\"contentUrl\":\"https:\\\/\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/shutterstock_1937410027-1.jpg\",\"width\":2048,\"height\":1887,\"caption\":\"Piloyada antigue\u00f1a recipe from Guatemala\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/\",\"name\":\"Growing Up Bilingual\",\"description\":\"Exploring the world through food, culture and familia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#organization\",\"name\":\"Growing Up Bilingual\",\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i1.wp.com\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/GUB_logo2017_512x512.png?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i1.wp.com\\\/growingupbilingual.com\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/GUB_logo2017_512x512.png?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Growing Up Bilingual\"},\"image\":{\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GrowUpBilingual\",\"https:\\\/\\\/x.com\\\/GrowUpBilingual\",\"https:\\\/\\\/www.instagram.com\\\/paulabendfeldt\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/paulabendfeldt\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/#\\\/schema\\\/person\\\/38bc5392534f86f23648e73caa28f6ff\",\"name\":\"Paula Bendfeldt-Diaz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g\",\"caption\":\"Paula Bendfeldt-Diaz\"},\"description\":\"Paula Bendfeldt-D\u00edaz is a Guatemalan travel writer, photographer, and founder of Growing Up Bilingual. After spending more than 15 years in the United States, she now lives in Guatemala and shares detailed travel guides, traditional Guatemalan recipes, and cultural insights based on a lifetime of firsthand experience. Through her writing, Paula helps travelers discover Guatemala beyond the typical tourist route with practical advice, local recommendations, and authentic experiences that connect visitors with the country\u2019s people, culture, and traditions. Planning a trip to Guatemala? Paula offers personalized Guatemala itinerary planning and trip consultation services tailored to your interests, travel style, and budget. Contact her at paula@growingupbilingual.com to learn more.\",\"sameAs\":[\"https:\\\/\\\/growingupbilingual.com\"],\"url\":\"https:\\\/\\\/growingupbilingual.com\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles","description":"This easy recipe for piloyada antigue\u00f1a, a bean and pork dish, is a delicious and hearty traditional Guatemalan dish that you will love.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/","og_locale":"es_ES","og_type":"article","og_title":"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles","og_description":"This easy recipe for piloyada antigue\u00f1a, a bean and pork dish, is a delicious and hearty traditional Guatemalan dish that you will love.","og_url":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/","og_site_name":"Growing Up Bilingual","article_publisher":"https:\/\/www.facebook.com\/GrowUpBilingual","article_published_time":"2023-12-01T15:07:43+00:00","article_modified_time":"2024-02-16T18:30:13+00:00","og_image":[{"width":2048,"height":1887,"url":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1.jpg","type":"image\/jpeg"}],"author":"Paula Bendfeldt-Diaz","twitter_card":"summary_large_image","twitter_creator":"@GrowUpBilingual","twitter_site":"@GrowUpBilingual","twitter_misc":{"Escrito por":"Paula Bendfeldt-Diaz","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#article","isPartOf":{"@id":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/"},"author":{"name":"Paula Bendfeldt-Diaz","@id":"https:\/\/growingupbilingual.com\/es\/#\/schema\/person\/38bc5392534f86f23648e73caa28f6ff"},"headline":"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles","datePublished":"2023-12-01T15:07:43+00:00","dateModified":"2024-02-16T18:30:13+00:00","mainEntityOfPage":{"@id":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/"},"wordCount":2223,"commentCount":0,"publisher":{"@id":"https:\/\/growingupbilingual.com\/es\/#organization"},"image":{"@id":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#primaryimage"},"thumbnailUrl":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1.jpg","keywords":["bean recipe","Guatemalan recipe","pork recipe","recipes @es"],"articleSection":["Food &amp; Recipes","Guatemalan recipes"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/","url":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/","name":"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles","isPartOf":{"@id":"https:\/\/growingupbilingual.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#primaryimage"},"image":{"@id":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#primaryimage"},"thumbnailUrl":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1.jpg","datePublished":"2023-12-01T15:07:43+00:00","dateModified":"2024-02-16T18:30:13+00:00","description":"This easy recipe for piloyada antigue\u00f1a, a bean and pork dish, is a delicious and hearty traditional Guatemalan dish that you will love.","breadcrumb":{"@id":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#primaryimage","url":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1.jpg","contentUrl":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1.jpg","width":2048,"height":1887,"caption":"Piloyada antigue\u00f1a recipe from Guatemala"},{"@type":"BreadcrumbList","@id":"https:\/\/growingupbilingual.com\/es\/piloyada-antiguena-receta-guatemalteca-de-cerdo-y-frijoles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/growingupbilingual.com\/es\/"},{"@type":"ListItem","position":2,"name":"Piloyada Antigue\u00f1a: Receta Guatemalteca de Cerdo y Frijoles"}]},{"@type":"WebSite","@id":"https:\/\/growingupbilingual.com\/es\/#website","url":"https:\/\/growingupbilingual.com\/es\/","name":"Growing Up Bilingual","description":"Exploring the world through food, culture and familia.","publisher":{"@id":"https:\/\/growingupbilingual.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/growingupbilingual.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/growingupbilingual.com\/es\/#organization","name":"Growing Up Bilingual","url":"https:\/\/growingupbilingual.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/growingupbilingual.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/i1.wp.com\/growingupbilingual.com\/wp-content\/uploads\/2017\/10\/GUB_logo2017_512x512.png?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i1.wp.com\/growingupbilingual.com\/wp-content\/uploads\/2017\/10\/GUB_logo2017_512x512.png?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Growing Up Bilingual"},"image":{"@id":"https:\/\/growingupbilingual.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GrowUpBilingual","https:\/\/x.com\/GrowUpBilingual","https:\/\/www.instagram.com\/paulabendfeldt\/","https:\/\/www.pinterest.com\/paulabendfeldt\/"]},{"@type":"Person","@id":"https:\/\/growingupbilingual.com\/es\/#\/schema\/person\/38bc5392534f86f23648e73caa28f6ff","name":"Paula Bendfeldt-Diaz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3821584b71d591c7ec341ce688911ea2f79492017562f16d208d095be113abdf?s=96&d=blank&r=g","caption":"Paula Bendfeldt-Diaz"},"description":"Paula Bendfeldt-D\u00edaz is a Guatemalan travel writer, photographer, and founder of Growing Up Bilingual. After spending more than 15 years in the United States, she now lives in Guatemala and shares detailed travel guides, traditional Guatemalan recipes, and cultural insights based on a lifetime of firsthand experience. Through her writing, Paula helps travelers discover Guatemala beyond the typical tourist route with practical advice, local recommendations, and authentic experiences that connect visitors with the country\u2019s people, culture, and traditions. Planning a trip to Guatemala? Paula offers personalized Guatemala itinerary planning and trip consultation services tailored to your interests, travel style, and budget. Contact her at paula@growingupbilingual.com to learn more.","sameAs":["https:\/\/growingupbilingual.com"],"url":"https:\/\/growingupbilingual.com\/es\/author\/admin\/"}]}},"mv":{"thumbnail_id":61662,"thumbnail_uri":"https:\/\/growingupbilingual.com\/wp-content\/uploads\/2023\/12\/shutterstock_1937410027-1-300x276.jpg"},"_links":{"self":[{"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/posts\/61695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/comments?post=61695"}],"version-history":[{"count":0,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/posts\/61695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/media\/61662"}],"wp:attachment":[{"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/media?parent=61695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/categories?post=61695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/growingupbilingual.com\/es\/wp-json\/wp\/v2\/tags?post=61695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}